{"id":53319,"date":"2021-01-22T13:40:10","date_gmt":"2021-01-22T12:40:10","guid":{"rendered":"https:\/\/alzira.es\/creu-roja-i-l-ajuntament-d-alzira-atenen-5-persones-amb-el-dispositiu-per-l-onada-de-fred-2\/"},"modified":"2022-01-10T10:46:58","modified_gmt":"2022-01-10T09:46:58","slug":"creu-roja-i-l-ajuntament-d-alzira-atenen-5-persones-amb-el-dispositiu-per-l-onada-de-fred-2","status":"publish","type":"post","link":"https:\/\/alzira.es\/es\/creu-roja-i-l-ajuntament-d-alzira-atenen-5-persones-amb-el-dispositiu-per-l-onada-de-fred-2\/","title":{"rendered":"Cruz Roja y el Ayuntamiento de Alzira atienden a 5 personas con el dispositivo por la ola de fr\u00edo"},"content":{"rendered":"<p>El pasado 5 de enero se pon\u00eda en marcha un <strong>protocolo de actuaci\u00f3n ante la ola de fr\u00edo<\/strong>, para atender a las personas de Alzira y pueblos del alrededor que lo necesitaron, que se mantuvo hasta el 17 de enero.<\/p>\n<p><strong>A lo largo de dos semanas los voluntarios de Cruz Roja atendieron un total de 5 personas que acudieron<\/strong> a pernoctar al albergue Provisional instalado en el Polideportivo P\u00e9rez Puig, <strong>donde adem\u00e1s tambi\u00e9n recibieron piezas de abrigo, higiene y alimento<\/strong>.<\/p>\n<p><em>\u00abLa valoraci\u00f3n de esta actuaci\u00f3n es positiva puesto que gracias a la acci\u00f3n del voluntariado de Cruz Roja y el trabajo de los diferentes departamento municipales, Servicios Sociales, Polic\u00eda Local y el departamento de Deportes, se ha dado respuesta a las necesidades de 5 personas en situaci\u00f3n de emergencia durante estos d\u00edas de fr\u00edo, para atenderlos\u00bb<\/em>, asegura la regidora de Servicios Sociales, <strong>Marina Mir<\/strong>.<\/p>\n<p>El albergue provisional ha sido al alcance de la ciudadan\u00eda desde las 19 horas hasta las 9 de la ma\u00f1ana, las horas m\u00e1s complicadas del d\u00eda en cuanto al fr\u00edo y las bajas temperaturas que hemos sufrido a lo largo de las dos \u00faltimas semanas.<\/p>\n<p>El protocolo de actuaci\u00f3n implica el registro del usuario, asignaci\u00f3n de cama, entrega del material de higiene personal, mantas y bebida caliente. As\u00ed mismo se ofrece la posibilidad de hacer uso de las duchas y se facilita ropa limpia.<\/p>\n<p><strong>En total se ha atendido:<\/strong><br \/>\n5 personas diferentes<br \/>\n\u2022 Se han distribuido 17 bebidas calientes<br \/>\n\u2022 Se han librado 4 kits de alimentaci\u00f3n de urgencia<br \/>\n\u2022 Se han librado 6 kits de higiene<br \/>\n\u2022 Se ha librado ropa de abrigo (mantas, y\/o saco de dormir) a 5 personas diferentes<br \/>\n\u2022 Se han librado 2 kits de ropa de hombre<br \/>\n\u2022 Se ha facilitado ducha e higiene personal a 3 personas distintas<\/p>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-53296\" src=\"https:\/\/alzira.es\/wp-content\/uploads\/2021\/01\/memoria_protocol_fred_22012021.jpeg\" alt=\"memoria protocol fred 22012021\" width=\"1200\" height=\"900\" srcset=\"https:\/\/alzira.es\/wp-content\/uploads\/2021\/01\/memoria_protocol_fred_22012021.jpeg 960w, https:\/\/alzira.es\/wp-content\/uploads\/2021\/01\/memoria_protocol_fred_22012021-680x510.jpeg 680w, https:\/\/alzira.es\/wp-content\/uploads\/2021\/01\/memoria_protocol_fred_22012021-768x576.jpeg 768w\" sizes=\"(max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 5 de enero se pon\u00eda en marcha un protocolo de actuaci\u00f3n ante la ola de fr\u00edo, para atender a las personas de Alzira y pueblos del alrededor que lo necesitaron, que se mantuvo hasta el 17 de enero. A lo largo de dos semanas los voluntarios de Cruz Roja atendieron un total de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/alzira.es\/es\/creu-roja-i-l-ajuntament-d-alzira-atenen-5-persones-amb-el-dispositiu-per-l-onada-de-fred-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCruz Roja y el Ayuntamiento de Alzira atienden a 5 personas con el dispositivo por la ola de fr\u00edo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":29,"featured_media":53296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5011],"tags":[],"class_list":["post-53319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicios-sociales"],"acf":[],"_links":{"self":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/posts\/53319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/comments?post=53319"}],"version-history":[{"count":0,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/posts\/53319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/media\/53296"}],"wp:attachment":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/media?parent=53319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/categories?post=53319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/tags?post=53319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}