{"id":127223,"date":"2022-08-23T13:06:03","date_gmt":"2022-08-23T11:06:03","guid":{"rendered":"https:\/\/alzira.es\/mas-de-4-600-alzirenos-y-alzirenas-han-visto-mejorada-su-agua-en-los-ultimos-siete-anos\/"},"modified":"2022-08-30T11:31:45","modified_gmt":"2022-08-30T09:31:45","slug":"mas-de-4-600-alzirenos-y-alzirenas-han-visto-mejorada-su-agua-en-los-ultimos-siete-anos","status":"publish","type":"post","link":"https:\/\/alzira.es\/es\/mas-de-4-600-alzirenos-y-alzirenas-han-visto-mejorada-su-agua-en-los-ultimos-siete-anos\/","title":{"rendered":"M\u00e1s de 4.600 alzire\u00f1os y alzire\u00f1as han visto mejorada su agua en los \u00faltimos siete a\u00f1os \u00a0"},"content":{"rendered":"<p>Un total de 4.696 alzire\u00f1os y alzire\u00f1as beben agua de calidad puesto que en los \u00faltimos siete a\u00f1os se ha conseguido que todos los pozos del casco urbano est\u00e9n adscritos y conectados al servicio municipal de aguas.<\/p>\n<p>El \u00faltimo pozo en pasar a la gesti\u00f3n p\u00fablica ha sido el servicio de abastecimiento de agua potable de la Cooperativa Valenciana de Consumo Sagrada Familia que dan suministro tanto al barrio de la Sagrada Familia como al del Torretx\u00f3. El Ayuntamiento recibe de esta manera las instalaciones as\u00ed como los bienes que no son de cesi\u00f3n obligatoria por parte de la cooperativa. Esta recepci\u00f3n tambi\u00e9n cuenta con la ocupaci\u00f3n de un trabajador de la cooperativa y el alquiler de la oficina situada en C\/Pere Esplugues, 141.<\/p>\n<p>Con esta \u00faltima operaci\u00f3n, el Ayuntamiento de Alzira ha solicitado a la Mercantil Aig\u00fces de Val\u00e8ncia, en su condici\u00f3n de concesionaria de la gesti\u00f3n del servicio municipal de abastecimiento de agua potable, que gestiono el aprovechamiento del volumen m\u00e1ximo anual de 97.000 m\u00b3\/a\u00f1o destinado proveer las nuevas zonas que ya han pasado a formar parte del servicio municipal de agua.<\/p>\n<p>El regidor de Servicios Urbanos, Fernando Pascual ha manifestado que \u201cEs muy importante este \u00faltimo acuerdo al cual hemos reunido, puesto que cerramos el c\u00edrculo de abastecimiento de agua potable, ofreciendo a todas las viviendas del casco urbano agua de la m\u00e1xima calidad. Como regidor de Servicios urbanos es motivo de satisfacci\u00f3n el hecho de haber podido conseguir que el agua que sale del grifo de los alzire\u00f1os y alzire\u00f1as sea apta para su consumo\u201d. El edil ha recordado que \u201cEn anteriores legislaturas los vecinos y vecinas de Alzira hemos sufrido los nitratos por arriba del permitido y los plaguicidas, el que hizo que se prohibiera su consumo a las embarazadas y personas vulnerables. Esto ya es cosa del pasado, ahora gracias al agua de la depuradora los nitratos son pr\u00e1cticamente insignificantes, oscilando entre los 7 y 8 miligramos, muy lejos de los 50 miligramos de m\u00e1ximo permitido\u201d.<\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"804\" height=\"1072\" data-id=\"127062\" src=\"https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-804x1072.jpeg\" alt=\"\" class=\"wp-image-127062\" srcset=\"https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-804x1072.jpeg 804w, https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-383x510.jpeg 383w, https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-768x1024.jpeg 768w, https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-300x400.jpeg 300w, https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-1152x1536.jpeg 1152w, https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-1536x2048.jpeg 1536w, https:\/\/alzira.es\/wp-content\/uploads\/2022\/08\/Pou-SF-3-scaled.jpeg 1920w\" sizes=\"(max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un total de 4.696 alzire\u00f1os y alzire\u00f1as beben agua de calidad puesto que en los \u00faltimos siete a\u00f1os se ha conseguido que todos los pozos del casco urbano est\u00e9n adscritos y conectados al servicio municipal de aguas. El \u00faltimo pozo en pasar a la gesti\u00f3n p\u00fablica ha sido el servicio de abastecimiento de agua potable &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/alzira.es\/es\/mas-de-4-600-alzirenos-y-alzirenas-han-visto-mejorada-su-agua-en-los-ultimos-siete-anos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abM\u00e1s de 4.600 alzire\u00f1os y alzire\u00f1as han visto mejorada su agua en los \u00faltimos siete a\u00f1os \u00a0\u00ab<\/span><\/a><\/p>\n","protected":false},"author":36,"featured_media":127062,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,1897],"tags":[],"class_list":["post-127223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-alzira","category-serveis-publics"],"acf":[],"_links":{"self":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/posts\/127223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/comments?post=127223"}],"version-history":[{"count":0,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/posts\/127223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/media\/127062"}],"wp:attachment":[{"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/media?parent=127223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/categories?post=127223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alzira.es\/es\/wp-json\/wp\/v2\/tags?post=127223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}